{"id":1828,"date":"2013-05-08T13:43:39","date_gmt":"2013-05-08T13:43:39","guid":{"rendered":"https:\/\/www.lymphoma.ca\/le-traitement-par-le-positivisme\/"},"modified":"2013-05-08T13:43:39","modified_gmt":"2013-05-08T13:43:39","slug":"le-traitement-par-le-positivisme","status":"publish","type":"post","link":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/","title":{"rendered":"Le traitement par le positivisme"},"content":{"rendered":"<p>Dans le miroir, Hayley Holroyd apercevait une femme en sant\u00e9, et non la r\u00e9flexion d\u2019une personne atteinte du lymphome de Hodgkin.<br \/>\n<!--more--><\/p>\n<h2>Vivre avec le lymphome<\/h2>\n<p>Dans le miroir, Hayley Holroyd apercevait une femme en sant\u00e9, et non la r\u00e9flexion d\u2019une personne atteinte du lymphome de Hodgkin.<\/p>\n<p>Quand ses cheveux se sont mis \u00e0 tomber des suites des traitements de chimioth\u00e9rapie, Holroyd a d\u00fb regarder la r\u00e9alit\u00e9 en face. Sa chevelure, qui faisait partie de son identit\u00e9, \u00e9tait en train de dispara\u00eetre.<\/p>\n<p>\u00ab&nbsp;J\u2019ai d\u00fb faire face au <em>vrai<\/em> moi, ce moi d\u00e9pourvu d\u2019une fausse identit\u00e9. Une version d\u00e9nud\u00e9e de Hayley, dit-elle. Ce peut \u00eatre plus \u00e9peurant encore que le cancer.&nbsp;\u00bb<\/p>\n<p>La perte de ses cheveux a \u00e9t\u00e9 un moment cl\u00e9 pour Holroyd, dans sa lutte contre le cancer. Elle affirme que cette perte lui a ouvert les yeux sur ce qui \u00e9tait r\u00e9ellement important&nbsp;: se sentir bien dans sa peau et dans sa vie.<\/p>\n<p>Le plan de traitement de Holroyd consistait en une biopsie chirurgicale et douze s\u00e9ances de chimioth\u00e9rapie r\u00e9parties sur une p\u00e9riode de six mois.<\/p>\n<p>Son plan de traitement ne s\u2019arr\u00eatait toutefois pas l\u00e0. Elle a chang\u00e9 sa fa\u00e7on de s\u2019alimenter et sa mani\u00e8re de penser.<\/p>\n<p>\u00ab&nbsp;Quand j\u2019ai re\u00e7u le diagnostic, je savais que le mieux que je pouvais faire pour mon corps et mon esprit \u00e9tait de rester positive, de me recentrer sur les bons c\u00f4t\u00e9s de la vie, et de me concentrer sur les activit\u00e9s qui me rendaient heureuse&nbsp;\u00bb, dit Holroyd.<\/p>\n<p>Elle a adopt\u00e9 l\u2019approche de la pens\u00e9e positive (<em>Positive Mental Attitude<\/em> ou PMA), une philosophie de d\u00e9veloppement personnel mise au point par Napoleon Hill. Ce dernier a \u00e9crit des livres sur l&rsquo;\u00e9panouissement personnel, dont <em>Le succ\u00e8s par la pens\u00e9e constructive<\/em>, publi\u00e9 dans les ann\u00e9es 60.<\/p>\n<p>Pour Holroyd, l\u2019adoption d\u2019une attitude positive (ou constructive) signifiait changer de perspective. Elle s\u2019est concentr\u00e9e sur ce qui \u00e9tait positif, a mis fin \u00e0 des relations conflictuelles, et a d\u00e9cid\u00e9 de rire plus.<\/p>\n<p>\u00ab&nbsp;Ce n\u2019est qu\u2019apr\u00e8s avoir \u00e9lagu\u00e9 tout ce qui m\u2019emp\u00eachait d\u2019avancer que j\u2019ai senti que commen\u00e7ait la gu\u00e9rison&nbsp;\u00bb, dit-elle.<\/p>\n<p>Le 23 novembre 2011, Holroyd a appris la bonne nouvelle&nbsp;: elle avait vaincu le cancer.<\/p>\n<p>\u00ab&nbsp;Je ne dis pas que la PMA, \u00e0 elle seule, est venue \u00e0 bout de mon cancer, mais elle a assur\u00e9ment \u00e9t\u00e9 un facteur d\u00e9terminant, en plus des quelques changements majeurs que j\u2019ai effectu\u00e9s dans mon mode de vie. Je crois que l\u2019un des pires ennemis est le stress&nbsp;\u00bb, dit-elle.<\/p>\n<p>\u00ab&nbsp;Si nous pouvions \u00e9liminer le stress de nos vies, que ce soit par la pens\u00e9e positive, dans l\u2019environnement, ou par nos habitudes alimentaires, nous serions tous heureux et en sant\u00e9.&nbsp;\u00bb<\/p>\n<p>Holroyd, maintenant d\u00e9barrass\u00e9e du cancer, voulait aider. Une attitude positive avait contribu\u00e9 \u00e0 son succ\u00e8s, et elle voulait inspirer cet \u00e9lan de positivisme chez d\u2019autres.<\/p>\n<p>Elle a donc d\u00e9cid\u00e9 de le faire \u00e0 travers P. M. Art, une entreprise d\u2019objets d\u2019art et de v\u00eatements.<\/p>\n<p>La mission de P. M. Art est d\u2019aider les gens \u00e0 se sentir bien, que ce soit par la cr\u00e9ation de T-shirts ou des citations inspirantes sur toile. Le style de Holroyd se caract\u00e9rise par des couleurs vives et des graphiques rappelant l\u2019esth\u00e9tique des bandes dessin\u00e9es. Ces articles servent \u00e0 nous faire penser de rester positif au quotidien.<\/p>\n<p class=\"Pa7 pullquote\">\u00ab&nbsp;J\u2019ai d\u00fb faire face au <em>vrai<\/em> moi, ce moi d\u00e9pourvu d\u2019une fausse identit\u00e9. Une version d\u00e9nud\u00e9e de Hayley; ce peut \u00eatre plus \u00e9peurant encore que le cancer.&nbsp;\u00bb<\/p>\n<p>\u00ab&nbsp;Mon objectif, en cr\u00e9ant P. M. Art, est d\u2019inspirer une attitude constructive, positive chez les autres&nbsp;\u00bb, dit-elle.<\/p>\n<p>\u00ab&nbsp;Je veux que les gens se rappellent, en portant un T-shirt ou en visitant mon site web, le pouvoir de la positivit\u00e9 et comment un simple changement de perspective peut avoir un impact b\u00e9n\u00e9fique sur leur vie enti\u00e8re.&nbsp;\u00bb<\/p>\n<p>Une attitude constructive, positive, a \u00e9t\u00e9 d\u2019une aide pr\u00e9cieuse pour Holroyd et elle souhaite transmettre cette attitude au monde entier.<\/p>\n<p><em>Pour de plus amples renseignements au sujet de P. M. Art, visitez <\/em><a href=\"http:\/\/www.positivementalart.com\">www.positivementalart.com<\/a><em> (en anglais seulement). Vous pouvez aussi suivre l\u2019entreprise sur Twitter&nbsp;: @_PMArt (en anglais seulement).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le miroir, Hayley Holroyd apercevait une femme en sant\u00e9, et non la r\u00e9flexion d\u2019une personne atteinte du lymphome de Hodgkin.<\/p>\n","protected":false},"author":1,"featured_media":1825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1828","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le traitement par le positivisme - Lymphoma Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le traitement par le positivisme - Lymphoma Canada\" \/>\n<meta property=\"og:description\" content=\"Dans le miroir, Hayley Holroyd apercevait une femme en sant\u00e9, et non la r\u00e9flexion d\u2019une personne atteinte du lymphome de Hodgkin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/\" \/>\n<meta property=\"og:site_name\" content=\"Lymphoma Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LymphomaCanada\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-08T13:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1097\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lymphomacanada\" \/>\n<meta name=\"twitter:site\" content=\"@lymphomacanada\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#\\\/schema\\\/person\\\/3f654528f96ee33030061e70192633c4\"},\"headline\":\"Le traitement par le positivisme\",\"datePublished\":\"2013-05-08T13:43:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/\"},\"wordCount\":763,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/hayleyholroyd-scaled.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/\",\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/\",\"name\":\"Le traitement par le positivisme - Lymphoma Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/hayleyholroyd-scaled.jpg\",\"datePublished\":\"2013-05-08T13:43:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/hayleyholroyd-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/hayleyholroyd-scaled.jpg\",\"width\":2560,\"height\":1097,\"caption\":\"hayleyholroyd\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/le-traitement-par-le-positivisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le traitement par le positivisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/\",\"name\":\"Lymphoma Canada\",\"description\":\"Information. Help. Hope.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#organization\",\"name\":\"Lymphoma Canada\",\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-lymphoma.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lymphoma.ca\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-lymphoma.jpg\",\"width\":343,\"height\":343,\"caption\":\"Lymphoma Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LymphomaCanada\",\"https:\\\/\\\/x.com\\\/lymphomacanada\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lymphoma-canada\\\/\",\"http:\\\/\\\/instagram.com\\\/lymphomacanada\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/LymphomaTV\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/#\\\/schema\\\/person\\\/3f654528f96ee33030061e70192633c4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.lymphoma.ca\\\/fr\\\/author\\\/erezz_oxmaxp0p\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le traitement par le positivisme - Lymphoma Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/","og_locale":"fr_FR","og_type":"article","og_title":"Le traitement par le positivisme - Lymphoma Canada","og_description":"Dans le miroir, Hayley Holroyd apercevait une femme en sant\u00e9, et non la r\u00e9flexion d\u2019une personne atteinte du lymphome de Hodgkin.","og_url":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/","og_site_name":"Lymphoma Canada","article_publisher":"https:\/\/www.facebook.com\/LymphomaCanada","article_published_time":"2013-05-08T13:43:39+00:00","og_image":[{"width":2560,"height":1097,"url":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@lymphomacanada","twitter_site":"@lymphomacanada","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#article","isPartOf":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/"},"author":{"name":"admin","@id":"https:\/\/www.lymphoma.ca\/fr\/#\/schema\/person\/3f654528f96ee33030061e70192633c4"},"headline":"Le traitement par le positivisme","datePublished":"2013-05-08T13:43:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/"},"wordCount":763,"commentCount":0,"publisher":{"@id":"https:\/\/www.lymphoma.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/","url":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/","name":"Le traitement par le positivisme - Lymphoma Canada","isPartOf":{"@id":"https:\/\/www.lymphoma.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#primaryimage"},"image":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg","datePublished":"2013-05-08T13:43:39+00:00","breadcrumb":{"@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#primaryimage","url":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg","contentUrl":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2013\/05\/hayleyholroyd-scaled.jpg","width":2560,"height":1097,"caption":"hayleyholroyd"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lymphoma.ca\/fr\/le-traitement-par-le-positivisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lymphoma.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Le traitement par le positivisme"}]},{"@type":"WebSite","@id":"https:\/\/www.lymphoma.ca\/fr\/#website","url":"https:\/\/www.lymphoma.ca\/fr\/","name":"Lymphoma Canada","description":"Information. Help. Hope.","publisher":{"@id":"https:\/\/www.lymphoma.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lymphoma.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lymphoma.ca\/fr\/#organization","name":"Lymphoma Canada","url":"https:\/\/www.lymphoma.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lymphoma.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2023\/05\/logo-lymphoma.jpg","contentUrl":"https:\/\/www.lymphoma.ca\/wp-content\/uploads\/2023\/05\/logo-lymphoma.jpg","width":343,"height":343,"caption":"Lymphoma Canada"},"image":{"@id":"https:\/\/www.lymphoma.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LymphomaCanada","https:\/\/x.com\/lymphomacanada","https:\/\/www.linkedin.com\/company\/lymphoma-canada\/","http:\/\/instagram.com\/lymphomacanada","http:\/\/www.youtube.com\/user\/LymphomaTV"]},{"@type":"Person","@id":"https:\/\/www.lymphoma.ca\/fr\/#\/schema\/person\/3f654528f96ee33030061e70192633c4","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aee8f4fe0d680167bf5d1a530e9f3514e7a8fa36199d4a3926a91e0b5960bf9f?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.lymphoma.ca\/fr\/author\/erezz_oxmaxp0p\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/posts\/1828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/comments?post=1828"}],"version-history":[{"count":0,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/posts\/1828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/media\/1825"}],"wp:attachment":[{"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/media?parent=1828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/categories?post=1828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lymphoma.ca\/fr\/wp-json\/wp\/v2\/tags?post=1828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}